{"id":13998,"date":"2024-06-28T15:20:20","date_gmt":"2024-06-28T07:20:20","guid":{"rendered":"https:\/\/www.paintinglantern.com\/?page_id=13998"},"modified":"2026-04-16T09:34:04","modified_gmt":"2026-04-16T01:34:04","slug":"lanternes-chinoises-geantes","status":"publish","type":"page","link":"https:\/\/www.paintinglantern.com\/fr\/lanternes-chinoises-geantes\/","title":{"rendered":"Grandes lanternes chinoises"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13998\" class=\"elementor elementor-13998 elementor-156\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-acecf1a e-flex e-con-boxed e-con e-parent\" data-id=\"acecf1a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-67eda24 e-con-full e-flex e-con e-child\" data-id=\"67eda24\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;wave-brush&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 283.5 27.8\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M283.5,9.7c0,0-7.3,4.3-14,4.6c-6.8,0.3-12.6,0-20.9-1.5c-11.3-2-33.1-10.1-44.7-5.7\ts-12.1,4.6-18,7.4c-6.6,3.2-20,9.6-36.6,9.3C131.6,23.5,99.5,7.2,86.3,8c-1.4,0.1-6.6,0.8-10.5,2c-3.8,1.2-9.4,3.8-17,4.7\tc-3.2,0.4-8.3,1.1-14.2,0.9c-1.5-0.1-6.3-0.4-12-1.6c-5.7-1.2-11-3.1-15.8-3.7C6.5,9.2,0,10.8,0,10.8V0h283.5V9.7z M260.8,11.3\tc-0.7-1-2-0.4-4.3-0.4c-2.3,0-6.1-1.2-5.8-1.1c0.3,0.1,3.1,1.5,6,1.9C259.7,12.2,261.4,12.3,260.8,11.3z M242.4,8.6\tc0,0-2.4-0.2-5.6-0.9c-3.2-0.8-10.3-2.8-15.1-3.5c-8.2-1.1-15.8,0-15.1,0.1c0.8,0.1,9.6-0.6,17.6,1.1c3.3,0.7,9.3,2.2,12.4,2.7\tC239.9,8.7,242.4,8.6,242.4,8.6z M185.2,8.5c1.7-0.7-13.3,4.7-18.5,6.1c-2.1,0.6-6.2,1.6-10,2c-3.9,0.4-8.9,0.4-8.8,0.5\tc0,0.2,5.8,0.8,11.2,0c5.4-0.8,5.2-1.1,7.6-1.6C170.5,14.7,183.5,9.2,185.2,8.5z M199.1,6.9c0.2,0-0.8-0.4-4.8,1.1\tc-4,1.5-6.7,3.5-6.9,3.7c-0.2,0.1,3.5-1.8,6.6-3C197,7.5,199,6.9,199.1,6.9z M283,6c-0.1,0.1-1.9,1.1-4.8,2.5s-6.9,2.8-6.7,2.7\tc0.2,0,3.5-0.6,7.4-2.5C282.8,6.8,283.1,5.9,283,6z M31.3,11.6c0.1-0.2-1.9-0.2-4.5-1.2s-5.4-1.6-7.8-2C15,7.6,7.3,8.5,7.7,8.6\tC8,8.7,15.9,8.3,20.2,9.3c2.2,0.5,2.4,0.5,5.7,1.6S31.2,11.9,31.3,11.6z M73,9.2c0.4-0.1,3.5-1.6,8.4-2.6c4.9-1.1,8.9-0.5,8.9-0.8\tc0-0.3-1-0.9-6.2-0.3S72.6,9.3,73,9.2z M71.6,6.7C71.8,6.8,75,5.4,77.3,5c2.3-0.3,1.9-0.5,1.9-0.6c0-0.1-1.1-0.2-2.7,0.2\tC74.8,5.1,71.4,6.6,71.6,6.7z M93.6,4.4c0.1,0.2,3.5,0.8,5.6,1.8c2.1,1,1.8,0.6,1.9,0.5c0.1-0.1-0.8-0.8-2.4-1.3\tC97.1,4.8,93.5,4.2,93.6,4.4z M65.4,11.1c-0.1,0.3,0.3,0.5,1.9-0.2s2.6-1.3,2.2-1.2s-0.9,0.4-2.5,0.8C65.3,10.9,65.5,10.8,65.4,11.1\tz M34.5,12.4c-0.2,0,2.1,0.8,3.3,0.9c1.2,0.1,2,0.1,2-0.2c0-0.3-0.1-0.5-1.6-0.4C36.6,12.8,34.7,12.4,34.5,12.4z M152.2,21.1\tc-0.1,0.1-2.4-0.3-7.5-0.3c-5,0-13.6-2.4-17.2-3.5c-3.6-1.1,10,3.9,16.5,4.1C150.5,21.6,152.3,21,152.2,21.1z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M269.6,18c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC267.7,18.8,269.7,18,269.6,18z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M227.4,9.8c-0.2-0.1-4.5-1-9.5-1.2c-5-0.2-12.7,0.6-12.3,0.5c0.3-0.1,5.9-1.8,13.3-1.2\tS227.6,9.9,227.4,9.8z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M204.5,13.4c-0.1-0.1,2-1,3.2-1.1c1.2-0.1,2,0,2,0.3c0,0.3-0.1,0.5-1.6,0.4\tC206.4,12.9,204.6,13.5,204.5,13.4z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M201,10.6c0-0.1-4.4,1.2-6.3,2.2c-1.9,0.9-6.2,3.1-6.1,3.1c0.1,0.1,4.2-1.6,6.3-2.6\tS201,10.7,201,10.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M154.5,26.7c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC152.6,27.5,154.6,26.8,154.5,26.7z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M41.9,19.3c0,0,1.2-0.3,2.9-0.1c1.7,0.2,5.8,0.9,8.2,0.7c4.2-0.4,7.4-2.7,7-2.6\tc-0.4,0-4.3,2.2-8.6,1.9c-1.8-0.1-5.1-0.5-6.7-0.4S41.9,19.3,41.9,19.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M75.5,12.6c0.2,0.1,2-0.8,4.3-1.1c2.3-0.2,2.1-0.3,2.1-0.5c0-0.1-1.8-0.4-3.4,0\tC76.9,11.5,75.3,12.5,75.5,12.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M15.6,13.2c0-0.1,4.3,0,6.7,0.5c2.4,0.5,5,1.9,5,2c0,0.1-2.7-0.8-5.1-1.4\tC19.9,13.7,15.7,13.3,15.6,13.2z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87141a9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"87141a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Grandes lanternes chinoises : conception &amp; fabrication sur mesure<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a206a28 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a206a28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Les grandes lanternes chinoises sont des installations lumineuses et ombrag\u00e9es embl\u00e9matiques qui allient <a style=\"color: #008080; text-decoration: underline;\" href=\"https:\/\/www.paintinglantern.com\/fr\/lanternes-chinoises-symbole-culture\/\" target=\"_blank\" rel=\"noopener\">l&rsquo;art traditionnel des lanternes<\/a> \u00e0 une technologie de pointe. <strong>ForestPaintingLantern<\/strong> est sp\u00e9cialis\u00e9 dans la conception sur mesure, la fabrication haut de gamme et l&rsquo;installation de projets \u00e0 grande \u00e9chelle dans le monde entier, transformant votre vision ambitieuse en un spectacle urbain \u00e9poustouflant.<\/p><p><strong>Construisez de nouveaux monuments embl\u00e9matiques pour votre ville<\/strong> : <a href=\"https:\/\/www.paintinglantern.com\/fr\/contact-fabricant-lanternes\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><span style=\"color: #008080; text-decoration: underline;\">contactez-nous<\/span><\/span><\/a> pour lancer votre projet d&rsquo;ing\u00e9nierie de lanternes g\u00e9antes et cr\u00e9er une merveille \u00e0 couper le souffle sous le ciel nocturne de votre ville !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a57dd70 elementor-widget__width-initial elementor-widget elementor-widget-video\" data-id=\"a57dd70\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mute&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.paintinglantern.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/giant-chinese-dragon-lantern.jpg&quot;,&quot;id&quot;:13985,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;La nuit, dans le parc, une lanterne g\\u00e9ante en forme de dragon chinois, longue d&#039;une centaine de m\\u00e8tres, attire tous les regards.&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/07\/custom-big-chinese-lanterns-display.mp4\" controls=\"\" preload=\"metadata\" muted=\"muted\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2025\/05\/giant-chinese-dragon-lantern.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Lire la vid\u00e9o sur La nuit, dans le parc, une lanterne g\u00e9ante en forme de dragon chinois, longue d&#039;une centaine de m\u00e8tres, attire tous les regards.\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-play\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M838 162C746 71 633 25 500 25 371 25 258 71 163 162 71 254 25 367 25 500 25 633 71 746 163 837 254 929 367 979 500 979 633 979 746 933 838 837 929 746 975 633 975 500 975 367 929 254 838 162M808 192C892 279 933 379 933 500 933 621 892 725 808 808 725 892 621 938 500 938 379 938 279 896 196 808 113 725 67 621 67 500 67 379 108 279 196 192 279 108 383 62 500 62 621 62 721 108 808 192M438 392V642L642 517 438 392Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ebd5f3 elementor-widget elementor-widget-spacer\" data-id=\"9ebd5f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb0817a e-con-full e-flex e-con e-child\" data-id=\"eb0817a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1e5076 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c1e5076\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi choisir notre s\u00e9rie de grandes lanternes ?<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c53f71d e-grid e-con-full e-con e-child\" data-id=\"c53f71d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a7f9a14 e-con-full e-flex e-con e-child\" data-id=\"a7f9a14\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0c0040d e-con-full e-flex e-con e-child\" data-id=\"0c0040d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47db11d elementor-widget elementor-widget-image\" data-id=\"47db11d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"424\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/big-dragon-head-lantern-1024x482.jpg\" class=\"attachment-large size-large wp-image-13986\" alt=\"Le mod\u00e8le de production modulaire pour les grandes lanternes : la t\u00eate de la lanterne dragon fabriqu\u00e9e s\u00e9par\u00e9ment.\" srcset=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/big-dragon-head-lantern-1024x482.jpg 1024w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/big-dragon-head-lantern-300x141.jpg 300w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/big-dragon-head-lantern-768x362.jpg 768w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/big-dragon-head-lantern-1536x724.jpg 1536w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/big-dragon-head-lantern.jpg 1560w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68cb88c e-con-full e-flex e-con e-child\" data-id=\"68cb88c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17bc5fa elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"17bc5fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Structure et s\u00e9curit\u00e9 de qualit\u00e9 technique<\/strong> : pour les dimensions g\u00e9antes, nous utilisons de l&rsquo;acier haute r\u00e9sistance r\u00e9sistant aux intemp\u00e9ries, et la charpente est soumise \u00e0 une v\u00e9rification m\u00e9canique structurelle pr\u00e9cise. Toutes les structures sont con\u00e7ues de mani\u00e8re modulaire afin de garantir que les ensembles de lanternes puissent r\u00e9sister \u00e0 des tests rigoureux de r\u00e9sistance au vent, aux s\u00e9ismes et \u00e0 la pression pendant le transport, le levage et l&rsquo;exposition \u00e0 long terme en ext\u00e9rieur, garantissant ainsi leur s\u00e9curit\u00e9 et leur stabilit\u00e9. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d6a5d55 e-con-full e-flex e-con e-child\" data-id=\"d6a5d55\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5f32873 e-con-full e-flex e-con e-child\" data-id=\"5f32873\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a812fa4 elementor-widget elementor-widget-image\" data-id=\"a812fa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"424\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/giant-dragon-lantern-1024x482.jpg\" class=\"attachment-large size-large wp-image-13987\" alt=\"Un grand ensemble de lanternes chinoises, mesurant jusqu&#039;\u00e0 cent m\u00e8tres de long, produit \u00e0 l&#039;aide de techniques de fabrication modulaires.\" srcset=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/giant-dragon-lantern-1024x482.jpg 1024w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/giant-dragon-lantern-300x141.jpg 300w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/giant-dragon-lantern-768x362.jpg 768w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/giant-dragon-lantern-1536x724.jpg 1536w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/giant-dragon-lantern.jpg 1560w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e5b695 e-con-full e-flex e-con e-child\" data-id=\"5e5b695\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92598ec elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"92598ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Une taille et un impact visuel inimaginables<\/strong> : notre capacit\u00e9 de fabrication nous permet de personnaliser des ensembles de lanternes ultra-hautes de plus de 30 m\u00e8tres ou des grappes de lanternes de plusieurs centaines de m\u00e8tres de long. Nous utilisons la mod\u00e9lisation 3D et des techniques de production en blocs pour r\u00e9aliser n&rsquo;importe quelle conception complexe et massive, garantissant ainsi un rendu parfait des d\u00e9tails et un effet visuel global, cr\u00e9ant ainsi des merveilles visuelles embl\u00e9matiques. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a19c96d e-con-full e-flex e-con e-child\" data-id=\"a19c96d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4aafd4f e-con-full e-flex e-con e-child\" data-id=\"4aafd4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09cfa7c elementor-widget elementor-widget-image\" data-id=\"09cfa7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"424\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2025\/11\/installing-big-chinese-lanterns-1024x482.jpg\" class=\"attachment-large size-large wp-image-13907\" alt=\"Le processus d&#039;installation sur site des grandes lanternes chinoises.\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7547c26 e-con-full e-flex e-con e-child\" data-id=\"7547c26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc645f0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fc645f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Gestion de projet \u00ab cl\u00e9 en main \u00bb \u00e0 l&rsquo;\u00e9chelle mondiale<\/strong> : les projets de lanternes g\u00e9antes sont complexes, impliquant une logistique transfrontali\u00e8re, le levage de machines lourdes sur site et une collaboration interd\u00e9partementale. Nous fournissons un service \u00ab cl\u00e9 en main \u00bb complet \u00e0 l&rsquo;\u00e9chelle mondiale, couvrant tout, de la planification du th\u00e8me \u00e0 la production en usine, en passant par la logistique maritime, l&rsquo;installation sur site et le d\u00e9bogage, vous garantissant ainsi une livraison facile du projet. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f8c176e e-con-full e-flex e-con e-child\" data-id=\"f8c176e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-92064d2 e-con-full e-flex e-con e-child\" data-id=\"92064d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0dd5acc elementor-widget elementor-widget-image\" data-id=\"0dd5acc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"424\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/huge-lantern-landmark-1024x482.jpg\" class=\"attachment-large size-large wp-image-13988\" alt=\"Pendant la journ\u00e9e, la lanterne g\u00e9ante en forme de dragon du parc peut \u00e9galement servir d&#039;\u0153uvre d&#039;art embl\u00e9matique.\" srcset=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/huge-lantern-landmark-1024x482.jpg 1024w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/huge-lantern-landmark-300x141.jpg 300w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/huge-lantern-landmark-768x362.jpg 768w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/huge-lantern-landmark-1536x724.jpg 1536w, https:\/\/www.paintinglantern.com\/wp-content\/uploads\/2024\/08\/huge-lantern-landmark.jpg 1560w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1dc2dd0 e-con-full e-flex e-con e-child\" data-id=\"1dc2dd0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f6fc29 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5f6fc29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Rep\u00e8re artistique, de jour comme de nuit<\/strong> : nous ne nous contentons pas de fabriquer des lanternes, nous cr\u00e9ons des rep\u00e8res artistiques. De jour, l&rsquo;ensemble de lanternes est une sculpture raffin\u00e9e qui s&rsquo;int\u00e8gre \u00e0 son environnement. De nuit, il devient le centre lumineux et ombrag\u00e9 le plus anim\u00e9 de la ville gr\u00e2ce \u00e0 des effets d&rsquo;\u00e9clairage dynamiques intelligents. Nous veillons \u00e0 ce que la valeur artistique et esth\u00e9tique de nos grandes lanternes ne soit pas limit\u00e9e par leur taille.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e84f83 e-con-full e-flex e-con e-child\" data-id=\"5e84f83\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee0289d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ee0289d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Impact urbain des lanternes g\u00e9antes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc252a1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"bc252a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. Monuments embl\u00e9matiques du centre-ville et principales f\u00eates<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb3a213 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"cb3a213\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Les lanternes g\u00e9antes sont incontestablement le point central des c\u00e9l\u00e9brations festives de la ville (telles que la f\u00eate du printemps, la f\u00eate des lanternes et les anniversaires de la ville). Elles peuvent rapidement devenir le centre d&rsquo;int\u00e9r\u00eat des actualit\u00e9s locales et un lieu tr\u00e8s pris\u00e9 sur les r\u00e9seaux sociaux, attirant des foules immenses et apportant une valeur commerciale et culturelle consid\u00e9rable \u00e0 la ville. Nous sommes sp\u00e9cialis\u00e9s dans la conception de lanternes g\u00e9antes qui s&rsquo;int\u00e8grent parfaitement au paysage urbain.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd43797 elementor-widget elementor-widget-image\" data-id=\"cd43797\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/custom-huge-dragon-lantern-rj8s8aurc110fm9kbsug41miixgk5lprff31tmki46.jpg\" title=\"Grande lanterne dragon personnalis\u00e9e\" alt=\"Une immense lanterne en forme de dragon, sp\u00e9cialement con\u00e7ue pour les c\u00e9l\u00e9brations du Nouvel An, est enroul\u00e9e sur la sc\u00e8ne.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">L'image montre un grand ensemble personnalis\u00e9 de lanternes Dragon enroul\u00e9es sur une sc\u00e8ne pour c\u00e9l\u00e9brer le Nouvel An.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f22c41 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"0f22c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Festivals culturels internationaux et grands parcs \u00e0 th\u00e8me<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5055872 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5055872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Les grandes lanternes repr\u00e9sentent l&rsquo;image d&rsquo;une nation ou d&rsquo;une ville, mettant en valeur le charme artistique et la puissance technique des lanternes chinoises lors de festivals culturels internationaux, d&rsquo;expositions ou dans les grands parcs d&rsquo;attractions internationaux. Nos ensembles de grandes lanternes peuvent servir de d\u00e9cor permanent \u00e0 l&rsquo;entr\u00e9e des parcs d&rsquo;attractions ou des complexes touristiques, \u00e9tablissant rapidement une identit\u00e9 visuelle forte et une atmosph\u00e8re th\u00e9matique, et offrant aux visiteurs une premi\u00e8re impression marquante. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2472185 elementor-widget elementor-widget-image\" data-id=\"2472185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/large-outdoor-lanterns-rj8rqodp6uwgqtv68ol9uzqdjubstwqy06qavup8s6.jpg\" title=\"Grandes lanternes d&rsquo;ext\u00e9rieur\" alt=\"Une grande lanterne d&#039;ext\u00e9rieur raffin\u00e9e en forme de demi-corps humain.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Il s'agit d'une photographie d'une immense exposition de lanternes en plein air repr\u00e9sentant des d\u00e9esses, qui met en valeur une esth\u00e9tique orientale profonde.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b5f3e0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5b5f3e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. \u00c9clairage commercial immobilier et paysager en bord de mer<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b251fd7 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b251fd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Nous personnalisons les installations d&rsquo;\u00e9clairage g\u00e9antes pour les grandes entr\u00e9es de complexes commerciaux, d&rsquo;attractions touristiques ou de zones urbaines en bord de mer. Nous disposons des comp\u00e9tences techniques n\u00e9cessaires pour cr\u00e9er des ensembles de lanternes flottantes sur l&rsquo;eau, ce qui nous permet de personnaliser des lanternes aquatiques pouvant atteindre plusieurs dizaines de m\u00e8tres de haut. Amplifi\u00e9es par les reflets \u00e0 la surface de l&rsquo;eau, elles cr\u00e9ent une exp\u00e9rience nocturne encore plus spectaculaire et immersive. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e50588 elementor-widget elementor-widget-image\" data-id=\"2e50588\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/lotus-large-water-lanterns-r1hhilt6msc35tvits5j54lr0gvci996u65qm5t392.jpg\" title=\"Grandes lanternes aquatiques Lotus\" alt=\"Une grande lanterne en forme de lotus bleu install\u00e9e sur l&#039;eau, avec une forme fid\u00e8lement reproduite et des couleurs vives.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">La photo montre un artisan installant une immense lanterne en forme de lotus flottant sur l'eau, magnifiquement con\u00e7ue.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8495d09 elementor-widget elementor-widget-spacer\" data-id=\"8495d09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2937fe1 e-con-full e-flex e-con e-child\" data-id=\"2937fe1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3ea60c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f3ea60c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le processus de fabrication des grandes lanternes\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fad4c4 elementor-widget elementor-widget-spacer\" data-id=\"6fad4c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b98394 e-grid e-con-full e-con e-child\" data-id=\"3b98394\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-cd33173 e-con-full e-flex e-con e-child\" data-id=\"cd33173\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d0be2f elementor-widget elementor-widget-image\" data-id=\"8d0be2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/design-large-lanterns-rj8ryn22ylyz7xpssukpclfjvgfilsvzy1tjmw6wtc.jpg\" title=\"Conception de grandes lanternes\" alt=\"Le concepteur est actuellement en train de r\u00e9diger les plans techniques pour le grand ensemble de lanternes.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a04e8f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3a04e8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong><b>\u00c9tapes 1-2 : Plan cr\u00e9atif et conception modulaire :<\/b><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce59a4f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ce59a4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>De la planification du th\u00e8me au dessin technique, le plan de blocage modulaire des ensembles de lanternes g\u00e9antes doit \u00eatre d\u00e9termin\u00e9 d\u00e8s la phase de conception afin de garantir une fabrication et un assemblage sur site efficaces.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-839f317 e-con-full e-flex e-con e-child\" data-id=\"839f317\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b576638 elementor-widget elementor-widget-image\" data-id=\"b576638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/anti-rust-lantern-framework-r64i5s47l9bkay2ooy2l3j3qh87t1utn69lpc8uysg.jpg\" title=\"Cadre de lanterne antirouille\" alt=\"Composants de lanterne haute r\u00e9sistance ayant subi un traitement antirouille.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb834fb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"eb834fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><b>\u00c9tape 3 : Structure haute r\u00e9sistance et v\u00e9rification m\u00e9canique :<\/b><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7067565 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7067565\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>De l&rsquo;acier \u00e0 haute r\u00e9sistance est utilis\u00e9 et la structure soud\u00e9e est soumise \u00e0 une v\u00e9rification m\u00e9canique structurelle. Toutes les structures sont rigoureusement trait\u00e9es contre la rouille afin de garantir la s\u00e9curit\u00e9 structurelle d&rsquo;une exposition ext\u00e9rieure \u00e0 long terme. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c05fdfd e-con-full e-flex e-con e-child\" data-id=\"c05fdfd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3e7629 elementor-widget elementor-widget-image\" data-id=\"d3e7629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/coloring-chinese-lantern-rc2efn4bfuq0yda8sxmj335r423fwnr8zotqmh1acg.jpg\" title=\"Coloriage Lanterne chinoise\" alt=\"Le processus moderne de fabrication des lanternes : pulv\u00e9risation de couleur\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2951fe elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e2951fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><b>\u00c9tapes 4-5 : Fabrication modulaire et coloration artistique :<\/b><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bdf0eb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6bdf0eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Les surfaces en soie sont finement fabriqu\u00e9es en modules \u00e0 l&rsquo;usine, ce qui garantit la pr\u00e9cision dimensionnelle et l&rsquo;uniformit\u00e9 des couleurs de chaque pi\u00e8ce. La coloration artistique est r\u00e9alis\u00e9e par des ma\u00eetres artisans, qui veillent \u00e0 la coh\u00e9rence de l&rsquo;effet final. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62cb150 e-con-full e-flex e-con e-child\" data-id=\"62cb150\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e0e6fa elementor-widget elementor-widget-image\" data-id=\"3e0e6fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/installing-large-outdoor-lantern-r4c7okzaw8vrdyrhywej3cevbvspgzfwwmiarq14m8.jpg\" title=\"Installation d&rsquo;une grande lanterne d&rsquo;ext\u00e9rieur\" alt=\"La lanterne g\u00e9ante de 10 m\u00e8tres de haut est actuellement en cours d&#039;installation avec beaucoup d&#039;intensit\u00e9.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2548d3 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c2548d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><b>\u00c9tape 6 : Syst\u00e8me d&rsquo;\u00e9clairage et levage lourd sur site :<\/b><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52a6b75 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"52a6b75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Des syst\u00e8mes LED intelligents \u00e9tanches sont int\u00e9gr\u00e9s. Nous fournissons \u00e9galement des services de levage de machines lourdes sur site, de c\u00e2blage \u00e9lectrique et d&rsquo;accompagnement interd\u00e9partemental afin de garantir l&rsquo;installation et le d\u00e9bogage s\u00fbrs et pr\u00e9cis de l&rsquo;ensemble de lanternes. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a39f29 elementor-widget elementor-widget-spacer\" data-id=\"4a39f29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3704af7 e-con-full e-flex e-con e-child\" data-id=\"3704af7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5dd4344 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5dd4344\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Galerie d'images des produits\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a3b90a elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3a3b90a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;slides_to_show&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Popular product images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 6\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/big-chinese-dragon-lantern-r5rxr87wsnt12ku4vo66cbwc0e33kqt8jxix1kzw68.jpg\" alt=\"Une sc\u00e8ne du festival des lanternes en forme de dragons, avec l&#039;ensemble des lanternes en forme de dragons d\u00e9j\u00e0 enti\u00e8rement install\u00e9es.\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Grande lanterne chinoise en forme de dragon<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 6\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/giant-chinese-dragon-lantern-r5rxr1n1gtk0tb3oy3bscvk3uozj2v3470yion9nds.jpg\" alt=\"La nuit, dans le parc, une lanterne g\u00e9ante en forme de dragon chinois, longue d&#039;une centaine de m\u00e8tres, attire tous les regards.\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Une lanterne chinoise g\u00e9ante en forme de dragon<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 6\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/custom-large-holiday-lanterns-r5rxqv264zb0k1d90ihedf7vozvykzczu4e4bpjelc.jpg\" alt=\"Une exposition de lanternes sp\u00e9cialement con\u00e7ues pour le festival : un dragon chinois et des kiosques.\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Grandes lanternes festives fabriqu\u00e9es sur mesure<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 6\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/huge-phoenix-lantern-r5rxqnjgmb0pz5o68f8dth46xwx0vej55368hhujz4.jpg\" alt=\"La lanterne g\u00e9ante \u00ab Phoenix \u00bb au Festival des lanternes de Singapour.\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Une immense lanterne Phoenix<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 6\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/large-outdoor-chinese-lanterns-r5rxqgylagrppvxqaudzu0rys7tgdit0s6lu4k4b6o.jpg\" alt=\"Types de lanternes chinoises : grandes lanternes d&#039;ext\u00e9rieur\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Grandes lanternes chinoises pour l'ext\u00e9rieur<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 6\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/www.paintinglantern.com\/wp-content\/uploads\/elementor\/thumbs\/large-chinese-lanterns-r5rxqadpymipgm7ad9jlukfqmipvvn2wfa1frme2e8.jpg\" alt=\"De grandes lanternes chinoises pour l&#039;ext\u00e9rieur, repr\u00e9sentant des divinit\u00e9s et des cr\u00e9atures mythiques.\" \/><div class=\"swiper-lazy-preloader\"><\/div><figcaption class=\"elementor-image-carousel-caption\">Grandes lanternes chinoises<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26bfca8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"26bfca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Engagement envers une qualit\u00e9 d&rsquo;ing\u00e9nierie exceptionnelle : Contactez-nous d\u00e8s maintenant pour que notre \u00e9quipe de professionnels vous fournisse des solutions \u00ab cl\u00e9s en main \u00bb s\u00fbres, efficaces et compl\u00e8tes pour votre projet \u00e0 grande \u00e9chelle.<\/p><p><strong>Exploration approfondie<\/strong> : <span style=\"text-decoration: underline;\"><span style=\"color: #008080;\"><a style=\"color: #008080; text-decoration: underline;\" href=\"https:\/\/www.paintinglantern.com\/fr\/lanternes-chinoises-symbole-culture\/\" target=\"_blank\" rel=\"noopener\">le d\u00e9veloppement moderne des lanternes chinoises<\/a><\/span><\/span>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2325147 elementor-widget elementor-widget-spacer\" data-id=\"2325147\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90c86d2 e-con-full e-flex e-con e-child\" data-id=\"90c86d2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48fa3df elementor-widget elementor-widget-spacer\" data-id=\"48fa3df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a83762e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"a83762e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">FAQ sur les grandes lanternes chinoises<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9729d6e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9729d6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Vous avez d&rsquo;autres questions ? N&rsquo;h\u00e9sitez pas \u00e0 nous contacter. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9ba5fa elementor-widget__width-initial elementor-widget elementor-widget-n-accordion\" data-id=\"e9ba5fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2450\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-2450\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 1. Quelle taille de lanterne peut \u00eatre consid\u00e9r\u00e9e comme une \u00ab grande lanterne \u00bb et comment d\u00e9terminer la taille la plus appropri\u00e9e pour un projet ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2450\" class=\"elementor-element elementor-element-64de7c3 e-con-full e-flex e-con e-child\" data-id=\"64de7c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b74980 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8b74980\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il n&rsquo;existe pas de norme absolue en mati\u00e8re de taille pour les \u00ab grandes lanternes \u00bb dans l&rsquo;industrie. Ce terme d\u00e9signe principalement un ensemble de lanternes qui produit un impact visuel remarquable sur le site du projet. Il s&rsquo;agit g\u00e9n\u00e9ralement d&rsquo;un assemblage de plus de 5 m\u00e8tres de hauteur ou d&rsquo;un groupe de lanternes d\u00e9passant 30 m\u00e8tres de longueur.  <\/p><p style=\"text-align: left;\"><strong>Principe de d\u00e9termination de la taille<\/strong> : la taille la plus adapt\u00e9e \u00e0 votre projet est d\u00e9termin\u00e9e conjointement par l&rsquo;espace disponible, les exigences de s\u00e9curit\u00e9 et la port\u00e9e visuelle.<\/p><p style=\"text-align: left;\"><strong>Notre suggestion<\/strong> : nous vous fournirons une solution de dimensionnement pr\u00e9cise, bas\u00e9e sur une simulation et une conception professionnelles, qui maximise l&rsquo;impact visuel de la lanterne g\u00e9ante, adapt\u00e9e aux photos de votre site, au flux pi\u00e9tonnier et au budget du projet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2451\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2451\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 2. Comment la s\u00e9curit\u00e9 structurelle et la r\u00e9sistance au vent et \u00e0 l'activit\u00e9 sismique sont-elles garanties pour les grandes lanternes ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2451\" class=\"elementor-element elementor-element-f086443 e-con-full e-flex e-con e-child\" data-id=\"f086443\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4164fe7 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4164fe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">La s\u00e9curit\u00e9 structurelle est notre priorit\u00e9 absolue. Nous fabriquons nos ensembles de lanternes g\u00e9antes en respectant strictement les normes les plus strictes en mati\u00e8re de projets d&rsquo;ing\u00e9nierie :<\/p><p style=\"text-align: left;\"><strong>Ch\u00e2ssis haute r\u00e9sistance<\/strong> : le ch\u00e2ssis est soud\u00e9 \u00e0 l&rsquo;aide d&rsquo;acier haute r\u00e9sistance et subit un traitement antirouille et anticorrosion rigoureux.<\/p><p style=\"text-align: left;\"><strong>V\u00e9rification m\u00e9canique<\/strong> : avant leur fabrication, tous les grands ensembles de lanternes doivent faire l&rsquo;objet d&rsquo;une v\u00e9rification et d&rsquo;un calcul professionnels de leur m\u00e9canique structurelle. Cela permet de s&rsquo;assurer qu&rsquo;ils peuvent r\u00e9sister aux normes locales maximales en mati\u00e8re de vent (comme des vents de force 8 \u00e0 10) et d&rsquo;activit\u00e9 sismique.<\/p><p style=\"text-align: left;\"><strong>Conception modulaire<\/strong> : les ensembles complexes de lanternes g\u00e9antes utilisent une conception modulaire, bas\u00e9e sur des blocs, afin de garantir la stabilit\u00e9 et la d\u00e9centralisation de la structure, ce qui facilite le transport et permet un assemblage efficace sur site.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2452\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2452\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 3. Comment se d\u00e9roulent le transport et l'installation sur site des ensembles de lanternes g\u00e9antes ? Cela implique-t-il l'utilisation d'engins lourds et une collaboration internationale ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2452\" class=\"elementor-element elementor-element-71989f8 e-con-full e-flex e-con e-child\" data-id=\"71989f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7212d2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a7212d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Le transport et l&rsquo;installation d&rsquo;ensembles de lanternes g\u00e9antes n\u00e9cessitent une gestion de projet sp\u00e9cialis\u00e9e :<\/p><p style=\"text-align: left;\"><strong>Transport segment\u00e9<\/strong> : une fois la fabrication termin\u00e9e \u00e0 l&rsquo;usine, l&rsquo;ensemble de lanternes est d\u00e9mont\u00e9 en segments et transport\u00e9 dans des conteneurs standard par voie maritime internationale. Cela permet d&rsquo;optimiser la s\u00e9curit\u00e9 et l&rsquo;efficacit\u00e9 du transport. <\/p><p style=\"text-align: left;\"><strong>Installation sur site<\/strong> : Des engins de levage lourds (tels que de grandes grues ou des chariots \u00e9l\u00e9vateurs) sont n\u00e9cessaires pour l&rsquo;assemblage sur site. Notre \u00e9quipe d&rsquo;ing\u00e9nieurs professionnels sera pr\u00e9sente sur place tout au long du processus afin de guider le soudage structurel pr\u00e9cis, le levage et l&rsquo;int\u00e9gration des syst\u00e8mes d&rsquo;\u00e9clairage et \u00e9lectriques, garantissant ainsi le placement s\u00fbr et pr\u00e9cis de l&rsquo;ensemble de lanternes. <\/p><p style=\"text-align: left;\"><strong>Service complet<\/strong> : nous nous occupons de toutes les formalit\u00e9s douani\u00e8res, de la logistique et de la coordination de l&rsquo;installation pour vous, vous offrant ainsi un v\u00e9ritable service \u00ab cl\u00e9 en main \u00bb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2453\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2453\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 4. Quel est le cycle complet type pour la personnalisation d'un projet de lanterne g\u00e9ante ? Que comprend le \u00ab service de projet tout-en-un \u00bb ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2453\" class=\"elementor-element elementor-element-6d61637 e-flex e-con-boxed e-con e-child\" data-id=\"6d61637\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2eaf31c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2eaf31c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Le cycle complet du projet d\u00e9pend de l&rsquo;ampleur et de la complexit\u00e9 de l&rsquo;ensemble de lanternes :<\/p><p style=\"text-align: left;\"><strong>D\u00e9lai <\/strong>: En g\u00e9n\u00e9ral, le cycle complet pour un ensemble de grandes lanternes, depuis l&rsquo;approbation de la conception jusqu&rsquo;\u00e0 l&rsquo;installation finale sur site, varie g\u00e9n\u00e9ralement entre 45 et 90 jours.<\/p><p style=\"text-align: left;\"><strong>Contenu du service tout-en-un<\/strong> : nos services couvrent : la planification th\u00e9matique, la conception artistique et les plans techniques, la production en usine selon des normes \u00e9lev\u00e9es, les tests de s\u00e9curit\u00e9 structurelle, la logistique internationale et le d\u00e9douanement, le levage lourd sur site, le d\u00e9bogage final et la r\u00e9ception du projet. Nous veillons \u00e0 ce que vous n&rsquo;ayez \u00e0 communiquer qu&rsquo;avec un seul chef de projet principal. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2454\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2454\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 5. Quelles sont les tendances en mati\u00e8re de conception des grandes lanternes et comment peuvent-elles \u00eatre int\u00e9gr\u00e9es dans le paysage urbain et la culture locale ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2454\" class=\"elementor-element elementor-element-aa2861d e-flex e-con-boxed e-con e-child\" data-id=\"aa2861d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7c1caa elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d7c1caa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">La tendance actuelle en mati\u00e8re de conception de grandes lanternes est de les transformer en rep\u00e8res urbains et d&rsquo;offrir des exp\u00e9riences immersives :<\/p><p style=\"text-align: left;\"><strong>Conception embl\u00e9matique<\/strong> : nous int\u00e9grons subtilement la conception des lanternes \u00e0 la silhouette de la ville, aux zones riveraines ou aux b\u00e2timents embl\u00e9matiques, cr\u00e9ant ainsi un nouveau centre urbain impressionnant de jour comme de nuit.<\/p><p style=\"text-align: left;\"><strong>Int\u00e9gration culturelle et propri\u00e9t\u00e9 intellectuelle<\/strong> : Int\u00e9grer des totems historiques locaux, des r\u00e9cits urbains ou des \u00e9l\u00e9ments de propri\u00e9t\u00e9 intellectuelle commerciale dans la conception des lanternes g\u00e9antes, afin de leur conf\u00e9rer une connotation culturelle unique et d&rsquo;en faire un vecteur culturel distinctif.<\/p><p style=\"text-align: left;\"><strong>Dynamique et interactif<\/strong> : en combinant des syst\u00e8mes de contr\u00f4le intelligents avec des effets lumineux dynamiques et une technologie interactive, cet ensemble de lanternes g\u00e9antes transcende l&rsquo;exposition statique pour devenir un centre d&rsquo;exp\u00e9rience immersif qui trouve un \u00e9cho aupr\u00e8s des visiteurs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a88d8ba elementor-widget elementor-widget-spacer\" data-id=\"a88d8ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Grandes lanternes chinoises : conception &amp; fabrication sur mesure Les grandes lanternes chinoises sont des installations lumineuses et ombrag\u00e9es embl\u00e9matiques qui allient l&rsquo;art traditionnel des lanternes \u00e0 une technologie de pointe. ForestPaintingLantern est sp\u00e9cialis\u00e9 dans la conception sur mesure, la fabrication haut de gamme et l&rsquo;installation de projets \u00e0 grande \u00e9chelle dans le monde entier, &#8230; <a title=\"Grandes lanternes chinoises\" class=\"read-more\" href=\"https:\/\/www.paintinglantern.com\/fr\/lanternes-chinoises-geantes\/\" aria-label=\"En savoir plus sur Grandes lanternes chinoises\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":13997,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13998","page","type-page","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.paintinglantern.com\/fr\/wp-json\/wp\/v2\/pages\/13998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.paintinglantern.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.paintinglantern.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.paintinglantern.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paintinglantern.com\/fr\/wp-json\/wp\/v2\/comments?post=13998"}],"version-history":[{"count":38,"href":"https:\/\/www.paintinglantern.com\/fr\/wp-json\/wp\/v2\/pages\/13998\/revisions"}],"predecessor-version":[{"id":21357,"href":"https:\/\/www.paintinglantern.com\/fr\/wp-json\/wp\/v2\/pages\/13998\/revisions\/21357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paintinglantern.com\/fr\/wp-json\/wp\/v2\/media\/13997"}],"wp:attachment":[{"href":"https:\/\/www.paintinglantern.com\/fr\/wp-json\/wp\/v2\/media?parent=13998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}